{"id":295,"count":6,"description":"","link":"https:\/\/lomonosov-porcelain.net\/et\/tootekategooria\/collections\/white-gold-collection\/","name":"White Gold Collection","slug":"white-gold-collection","taxonomy":"product_cat","parent":241,"meta":[],"menu_order":27,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>White Gold Collection | Lomonosov Porcelain Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lomonosov-porcelain.net\/et\/tootekategooria\/collections\/white-gold-collection\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"White Gold Collection | Lomonosov Porcelain Europe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lomonosov-porcelain.net\/et\/tootekategooria\/collections\/white-gold-collection\/\" \/>\n<meta property=\"og:site_name\" content=\"Lomonosov Porcelain Europe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product-category\\\/collections\\\/white-gold-collection\\\/\",\"url\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product-category\\\/collections\\\/white-gold-collection\\\/\",\"name\":\"White Gold Collection | Lomonosov Porcelain Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product-category\\\/collections\\\/white-gold-collection\\\/#breadcrumb\"},\"inLanguage\":\"et\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product-category\\\/collections\\\/white-gold-collection\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Collections\",\"item\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product-category\\\/collections\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"White Gold Collection\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/#website\",\"url\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/\",\"name\":\"Lomonosov Porcelain Europe\",\"description\":\"Heritage. Fashion. Style.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/#organization\",\"name\":\"Lomonosov Porcelain Europe\",\"alternateName\":\"Lomonosov Porcelain\",\"url\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product-category\\\/collections\\\/white-gold-collection\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product-category\\\/collections\\\/white-gold-collection\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lfzest\",\"https:\\\/\\\/www.instagram.com\\\/lomonosovporcelainestonia\\\/\"],\"legalName\":\"Lomonosov Porcelain O\u00dc\",\"address\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product-category\\\/collections\\\/white-gold-collection\\\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"59.43996967473164\",\"longitude\":\"24.747529771163688\"},\"telephone\":[\"+372 58053337\"],\"openingHoursSpecification\":[],\"email\":\"info@lomonosov-porcelain.net\",\"areaServed\":\"Europe\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product-category\\\/collections\\\/white-gold-collection\\\/#local-main-place-address\",\"streetAddress\":\"Pikk 36\",\"addressLocality\":\"Tallinn\",\"postalCode\":\"10123\",\"addressRegion\":\"Harjumaa\",\"addressCountry\":\"EE\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product-category\\\/collections\\\/white-gold-collection\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-ipm.png\",\"contentUrl\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-ipm.png\",\"width\":512,\"height\":512,\"caption\":\"Lomonosov Porcelain Europe\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"Tallinn\" \/>\n<meta name=\"geo.position\" content=\"59.43996967473164;24.747529771163688\" \/>\n<meta name=\"geo.region\" content=\"Estonia\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"White Gold Collection | Lomonosov Porcelain Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lomonosov-porcelain.net\/et\/tootekategooria\/collections\/white-gold-collection\/","og_locale":"et_EE","og_type":"article","og_title":"White Gold Collection | Lomonosov Porcelain Europe","og_url":"https:\/\/lomonosov-porcelain.net\/et\/tootekategooria\/collections\/white-gold-collection\/","og_site_name":"Lomonosov Porcelain Europe","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lomonosov-porcelain.net\/product-category\/collections\/white-gold-collection\/","url":"https:\/\/lomonosov-porcelain.net\/product-category\/collections\/white-gold-collection\/","name":"White Gold Collection | Lomonosov Porcelain Europe","isPartOf":{"@id":"https:\/\/lomonosov-porcelain.net\/#website"},"breadcrumb":{"@id":"https:\/\/lomonosov-porcelain.net\/product-category\/collections\/white-gold-collection\/#breadcrumb"},"inLanguage":"et"},{"@type":"BreadcrumbList","@id":"https:\/\/lomonosov-porcelain.net\/product-category\/collections\/white-gold-collection\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lomonosov-porcelain.net\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lomonosov-porcelain.net\/shop\/"},{"@type":"ListItem","position":3,"name":"Collections","item":"https:\/\/lomonosov-porcelain.net\/product-category\/collections\/"},{"@type":"ListItem","position":4,"name":"White Gold Collection"}]},{"@type":"WebSite","@id":"https:\/\/lomonosov-porcelain.net\/#website","url":"https:\/\/lomonosov-porcelain.net\/","name":"Lomonosov Porcelain Europe","description":"Heritage. Fashion. Style.","publisher":{"@id":"https:\/\/lomonosov-porcelain.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lomonosov-porcelain.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"},{"@type":["Organization","Place"],"@id":"https:\/\/lomonosov-porcelain.net\/#organization","name":"Lomonosov Porcelain Europe","alternateName":"Lomonosov Porcelain","url":"https:\/\/lomonosov-porcelain.net\/","logo":{"@id":"https:\/\/lomonosov-porcelain.net\/product-category\/collections\/white-gold-collection\/#local-main-organization-logo"},"image":{"@id":"https:\/\/lomonosov-porcelain.net\/product-category\/collections\/white-gold-collection\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/lfzest","https:\/\/www.instagram.com\/lomonosovporcelainestonia\/"],"legalName":"Lomonosov Porcelain O\u00dc","address":{"@id":"https:\/\/lomonosov-porcelain.net\/product-category\/collections\/white-gold-collection\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"59.43996967473164","longitude":"24.747529771163688"},"telephone":["+372 58053337"],"openingHoursSpecification":[],"email":"info@lomonosov-porcelain.net","areaServed":"Europe"},{"@type":"PostalAddress","@id":"https:\/\/lomonosov-porcelain.net\/product-category\/collections\/white-gold-collection\/#local-main-place-address","streetAddress":"Pikk 36","addressLocality":"Tallinn","postalCode":"10123","addressRegion":"Harjumaa","addressCountry":"EE"},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/lomonosov-porcelain.net\/product-category\/collections\/white-gold-collection\/#local-main-organization-logo","url":"https:\/\/lomonosov-porcelain.net\/wp-content\/uploads\/2022\/03\/cropped-logo-ipm.png","contentUrl":"https:\/\/lomonosov-porcelain.net\/wp-content\/uploads\/2022\/03\/cropped-logo-ipm.png","width":512,"height":512,"caption":"Lomonosov Porcelain Europe"}]},"geo.placename":"Tallinn","geo.position":{"lat":"59.43996967473164","long":"24.747529771163688"},"geo.region":"Estonia"},"_links":{"self":[{"href":"https:\/\/lomonosov-porcelain.net\/et\/wp-json\/wp\/v2\/product_cat\/295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lomonosov-porcelain.net\/et\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/lomonosov-porcelain.net\/et\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/lomonosov-porcelain.net\/et\/wp-json\/wp\/v2\/product_cat\/241"}],"wp:post_type":[{"href":"https:\/\/lomonosov-porcelain.net\/et\/wp-json\/wp\/v2\/product?product_cat=295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}