{"id":7368,"date":"2024-10-24T12:46:42","date_gmt":"2024-10-24T12:46:42","guid":{"rendered":"https:\/\/lomonosov-porcelain.net\/?post_type=product&#038;p=7368"},"modified":"2026-04-04T08:41:08","modified_gmt":"2026-04-04T08:41:08","slug":"lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml","status":"publish","type":"product","link":"https:\/\/lomonosov-porcelain.net\/et\/toode\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/","title":{"rendered":"Lomonosov Imperial Bone China Porcelain Coffee Mug Idyll Scarlet 1 400 Ml"},"content":{"rendered":"<p>Enjoy a steaming cup of hot tea or coffee with the Lomonosov Imperial Bone China Porcelain Scarlet Mug on Idyll form. This nice Tea Mug is made of porcelain by Lomonosov Imperial Porcelain Factory in St-Petersburg, Russia. The cup set will be a perfect gift for tea and coffee lovers and a perfect addition to any porcelain drinkware collection.<\/p>\n<p>Features:<\/p>\n<p>Overglaze polychrome decoration is used for the Scarlet Tea Coffee Mug. Embellished with 22-karat gold. Hand wash is recommended.<br \/>\nThe original Lomonosov factory logo is on the bottom of each piece. Genuine Article \u2013 100% Guaranteed.<br \/>\nMaterial: bone china porcelain. Made in Russia by the Imperial Lomonosov Porcelain Factory.<br \/>\nCup capacity 400 ml<br \/>\nProduced since 2021<\/p>","protected":false},"excerpt":{"rendered":"<p>Enjoy a steaming cup of hot tea or coffee with the Lomonosov Imperial Bone China Porcelain Scarlet Mug on Idyll form. This nice Tea Mug is made of porcelain by Lomonosov Imperial Porcelain Factory in St-Petersburg, Russia. The cup set will be a perfect gift for tea and coffee lovers and a perfect addition to&hellip;<\/p>","protected":false},"featured_media":6399,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[15,231,328],"product_tag":[233],"class_list":{"0":"post-7368","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-uncategorized","7":"product_cat-mugs","8":"product_cat-scarlet-collection","9":"product_tag-mugs","10":"product_shipping_class-size-m","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple","18":"col-xs-6 col-sm-4","19":"col-md-3 col-lg-3","20":"un-4-cols"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lomonosov Imperial Bone China Porcelain Coffee Mug Idyll Scarlet 1 400 Ml | Lomonosov Porcelain Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lomonosov-porcelain.net\/et\/toode\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lomonosov Imperial Bone China Porcelain Coffee Mug Idyll Scarlet 1 400 Ml | Lomonosov Porcelain Europe\" \/>\n<meta property=\"og:description\" content=\"Enjoy a steaming cup of hot tea or coffee with the Lomonosov Imperial Bone China Porcelain Scarlet Mug on Idyll form. This nice Tea Mug is made of porcelain by Lomonosov Imperial Porcelain Factory in St-Petersburg, Russia. The cup set will be a perfect gift for tea and coffee lovers and a perfect addition to&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lomonosov-porcelain.net\/et\/toode\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/\" \/>\n<meta property=\"og:site_name\" content=\"Lomonosov Porcelain Europe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lfzest\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-04T08:41:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lomonosov-porcelain.net\/wp-content\/uploads\/2023\/10\/skar-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"351\" \/>\n\t<meta property=\"og:image:height\" content=\"436\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product\\\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\\\/\",\"url\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product\\\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\\\/\",\"name\":\"Lomonosov Imperial Bone China Porcelain Coffee Mug Idyll Scarlet 1 400 Ml | Lomonosov Porcelain Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product\\\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product\\\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/skar-1.png\",\"datePublished\":\"2024-10-24T12:46:42+00:00\",\"dateModified\":\"2026-04-04T08:41:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product\\\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\\\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lomonosov-porcelain.net\\\/product\\\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product\\\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/skar-1.png\",\"contentUrl\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/skar-1.png\",\"width\":351,\"height\":436},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product\\\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Collections\",\"item\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product-category\\\/collections\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Lomonosov Imperial Bone China Porcelain Coffee Mug Idyll Scarlet 1 400 Ml\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/#website\",\"url\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/\",\"name\":\"Lomonosov Porcelain Europe\",\"description\":\"Heritage. Fashion. Style.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/#organization\",\"name\":\"Lomonosov Porcelain Europe\",\"alternateName\":\"Lomonosov Porcelain\",\"url\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product\\\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product\\\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lfzest\",\"https:\\\/\\\/www.instagram.com\\\/lomonosovporcelainestonia\\\/\"],\"legalName\":\"Lomonosov Porcelain O\u00dc\",\"address\":{\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product\\\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\\\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"59.43996967473164\",\"longitude\":\"24.747529771163688\"},\"telephone\":[\"+372 58053337\"],\"openingHoursSpecification\":[],\"email\":\"info@lomonosov-porcelain.net\",\"areaServed\":\"Europe\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product\\\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\\\/#local-main-place-address\",\"streetAddress\":\"Pikk 36\",\"addressLocality\":\"Tallinn\",\"postalCode\":\"10123\",\"addressRegion\":\"Harjumaa\",\"addressCountry\":\"EE\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/product\\\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-ipm.png\",\"contentUrl\":\"https:\\\/\\\/lomonosov-porcelain.net\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo-ipm.png\",\"width\":512,\"height\":512,\"caption\":\"Lomonosov Porcelain Europe\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"75.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"80.39540.00.1\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"Tallinn\" \/>\n<meta name=\"geo.position\" content=\"59.43996967473164;24.747529771163688\" \/>\n<meta name=\"geo.region\" content=\"Estonia\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lomonosov Imperial Bone China Porcelain Coffee Mug Idyll Scarlet 1 400 Ml | Lomonosov Porcelain Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lomonosov-porcelain.net\/et\/toode\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/","og_locale":"et_EE","og_type":"article","og_title":"Lomonosov Imperial Bone China Porcelain Coffee Mug Idyll Scarlet 1 400 Ml | Lomonosov Porcelain Europe","og_description":"Enjoy a steaming cup of hot tea or coffee with the Lomonosov Imperial Bone China Porcelain Scarlet Mug on Idyll form. This nice Tea Mug is made of porcelain by Lomonosov Imperial Porcelain Factory in St-Petersburg, Russia. The cup set will be a perfect gift for tea and coffee lovers and a perfect addition to&hellip;","og_url":"https:\/\/lomonosov-porcelain.net\/et\/toode\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/","og_site_name":"Lomonosov Porcelain Europe","article_publisher":"https:\/\/www.facebook.com\/lfzest","article_modified_time":"2026-04-04T08:41:08+00:00","og_image":[{"width":351,"height":436,"url":"https:\/\/lomonosov-porcelain.net\/wp-content\/uploads\/2023\/10\/skar-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lomonosov-porcelain.net\/product\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/","url":"https:\/\/lomonosov-porcelain.net\/product\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/","name":"Lomonosov Imperial Bone China Porcelain Coffee Mug Idyll Scarlet 1 400 Ml | Lomonosov Porcelain Europe","isPartOf":{"@id":"https:\/\/lomonosov-porcelain.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lomonosov-porcelain.net\/product\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/#primaryimage"},"image":{"@id":"https:\/\/lomonosov-porcelain.net\/product\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/#primaryimage"},"thumbnailUrl":"https:\/\/lomonosov-porcelain.net\/wp-content\/uploads\/2023\/10\/skar-1.png","datePublished":"2024-10-24T12:46:42+00:00","dateModified":"2026-04-04T08:41:08+00:00","breadcrumb":{"@id":"https:\/\/lomonosov-porcelain.net\/product\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lomonosov-porcelain.net\/product\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/lomonosov-porcelain.net\/product\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/#primaryimage","url":"https:\/\/lomonosov-porcelain.net\/wp-content\/uploads\/2023\/10\/skar-1.png","contentUrl":"https:\/\/lomonosov-porcelain.net\/wp-content\/uploads\/2023\/10\/skar-1.png","width":351,"height":436},{"@type":"BreadcrumbList","@id":"https:\/\/lomonosov-porcelain.net\/product\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lomonosov-porcelain.net\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lomonosov-porcelain.net\/shop\/"},{"@type":"ListItem","position":3,"name":"Collections","item":"https:\/\/lomonosov-porcelain.net\/product-category\/collections\/"},{"@type":"ListItem","position":4,"name":"Lomonosov Imperial Bone China Porcelain Coffee Mug Idyll Scarlet 1 400 Ml"}]},{"@type":"WebSite","@id":"https:\/\/lomonosov-porcelain.net\/#website","url":"https:\/\/lomonosov-porcelain.net\/","name":"Lomonosov Porcelain Europe","description":"Heritage. Fashion. Style.","publisher":{"@id":"https:\/\/lomonosov-porcelain.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lomonosov-porcelain.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"},{"@type":["Organization","Place"],"@id":"https:\/\/lomonosov-porcelain.net\/#organization","name":"Lomonosov Porcelain Europe","alternateName":"Lomonosov Porcelain","url":"https:\/\/lomonosov-porcelain.net\/","logo":{"@id":"https:\/\/lomonosov-porcelain.net\/product\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/#local-main-organization-logo"},"image":{"@id":"https:\/\/lomonosov-porcelain.net\/product\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/lfzest","https:\/\/www.instagram.com\/lomonosovporcelainestonia\/"],"legalName":"Lomonosov Porcelain O\u00dc","address":{"@id":"https:\/\/lomonosov-porcelain.net\/product\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"59.43996967473164","longitude":"24.747529771163688"},"telephone":["+372 58053337"],"openingHoursSpecification":[],"email":"info@lomonosov-porcelain.net","areaServed":"Europe"},{"@type":"PostalAddress","@id":"https:\/\/lomonosov-porcelain.net\/product\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/#local-main-place-address","streetAddress":"Pikk 36","addressLocality":"Tallinn","postalCode":"10123","addressRegion":"Harjumaa","addressCountry":"EE"},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/lomonosov-porcelain.net\/product\/lomonosov-imperial-bone-china-porcelain-coffee-mug-idyll-scarlet-1-400-ml\/#local-main-organization-logo","url":"https:\/\/lomonosov-porcelain.net\/wp-content\/uploads\/2022\/03\/cropped-logo-ipm.png","contentUrl":"https:\/\/lomonosov-porcelain.net\/wp-content\/uploads\/2022\/03\/cropped-logo-ipm.png","width":512,"height":512,"caption":"Lomonosov Porcelain Europe"}]},"product_price_amount":"75.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"80.39540.00.1","product_condition":"new","geo.placename":"Tallinn","geo.position":{"lat":"59.43996967473164","long":"24.747529771163688"},"geo.region":"Estonia"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lomonosov-porcelain.net\/et\/wp-json\/wp\/v2\/product\/7368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lomonosov-porcelain.net\/et\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lomonosov-porcelain.net\/et\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lomonosov-porcelain.net\/et\/wp-json\/wp\/v2\/comments?post=7368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lomonosov-porcelain.net\/et\/wp-json\/wp\/v2\/media\/6399"}],"wp:attachment":[{"href":"https:\/\/lomonosov-porcelain.net\/et\/wp-json\/wp\/v2\/media?parent=7368"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lomonosov-porcelain.net\/et\/wp-json\/wp\/v2\/product_cat?post=7368"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lomonosov-porcelain.net\/et\/wp-json\/wp\/v2\/product_tag?post=7368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}